{"id":3911,"date":"2021-09-22T14:35:12","date_gmt":"2021-09-22T11:35:12","guid":{"rendered":"https:\/\/tirsankardan.com\/centro-di-ricerca-e-sviluppo\/"},"modified":"2021-10-12T16:46:10","modified_gmt":"2021-10-12T13:46:10","slug":"centro-di-ricerca-e-sviluppo","status":"publish","type":"page","link":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/","title":{"rendered":"Centro di Ricerca e Sviluppo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3911\" class=\"elementor elementor-3911 elementor-1952\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ba25e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ba25e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a957a5\" data-id=\"4a957a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9244900 elementor-widget elementor-widget-text-editor\" data-id=\"9244900\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.3 - 28-12-2021 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div class=\"elementor-element elementor-element-e33b15b elementor-widget elementor-widget-heading\" data-id=\"e33b15b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\">\n<h2 class=\"elementor-heading-title elementor-size-default\" style=\"text-align: center;\"> <\/h2>\n<\/div>\n<div class=\"elementor-widget-container\">\n<h2 style=\"text-align: center;\"><span style=\"color: #2e3192;\">Generale<\/span><strong><br \/><\/strong><\/h2>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-4278092 elementor-widget elementor-widget-text-editor\" data-id=\"4278092\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>Il centro di ricerca e sviluppo Tirsan Kardan \u00e8 stato approvato e registrato dal Ministero dell&#8217;Industria e della Tecnologia all&#8217;inizio del 2016 in conformita\u2019 con la legge numero 5746.<\/p>\n<p>La nostra struttura, che si sviluppa su una superficie totale chiusa di 3.395 m2; Oltre ai centri di gestione del progetto, progettazione e simulazione, include anche un centro di prova di 1.865 m2 dotato con le ultime tecnologie.<\/p>\n<p>Il nostro equipaggio composto da piu\u2019 di 30 ricercatori e tecnici specializzati in macchinari, materiali e metallurgia, meccatronica, fisica e chimica, lavora con l&#8217;obiettivo di soddisfare tutte le esigenze e le aspettative dei nostri clienti nel processo da zero al prodotto finale.<\/p>\n<p>Il nostro centro di ricerca e sviluppo, risultato della valutazione delle prestazioni condotta dal ministero dell&#8217;Industria e della tecnologia nel 2018 \u00e9 stato il gruppo che ha ricevuto il primo premio nei centri di ricerca e sviluppo in Turchia.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0ad91f elementor-widget elementor-widget-spacer\" data-id=\"a0ad91f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.6.4 - 13-04-2022 *\/\n.e-container.e-container--row .elementor-spacer-inner{width:var(--spacer-size)}.e-container.e-container--column .elementor-spacer-inner,.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06e0554 elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06e0554\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f66cb11\" data-id=\"f66cb11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d517900 elementor-widget elementor-widget-sm-advantages\" data-id=\"d517900\" data-element_type=\"widget\" data-widget_type=\"sm-advantages.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t<div class=\"man_advantages\">\n\n\t\t\t<div class=\"man_adv_carousel owl-carousel\" data-items=\"3\">\n\n\t\t\t\t\t\t<div class=\"man_adv_box\" id=\"bae3cfe\">\n\t\t\t\t<div class=\"man_adv_box_img man_image_bck man_adv_box_img_bae3cfe\" data-image=\"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/DSF3656-web.jpg\"><\/div>\n\t\t\t\t<div class=\"man_adv_box_block\">\n\t\t\t\t\t<div class=\"man_adv_box_block_cont_wb man_wht_txt\">\n\t\t\t\t\t\t<h4>01<\/h4>\n\t\t\t\t\t\t<h2>Test e Verifica<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"man_adv_box_block_cont man_wht_txt\">\n\t\t\t\t\t\t<h4>01<\/h4>\n\t\t\t\t\t\t<h2>Test e Verifica<\/h2>\n\t\t\t\t\t\t<p>Il nostro centro di test, situato all&#039;interno del centro di ricerca e sviluppo Tirsan Kardan, dispone di un&#039;eccellente infrastruttura in grado di eseguire tutte le verifiche di prodotto e di processo, dal livello del prodotto assemblato ai componenti indipendenti.<\/p>\n\t\t\t\t\t\t<a href=\"https:\/\/tirsankardan.com\/it\/\/it\/centro-di-ricerca-e-sviluppo\/#test-it\" class=\"btn btn_transparent\">Di pi\u00f9<i class=\"ti ti-arrow-right\"><\/i><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"man_adv_box\" id=\"ed3439f\">\n\t\t\t\t<div class=\"man_adv_box_img man_image_bck man_adv_box_img_ed3439f\" data-image=\"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/DSF3590-web.jpg\"><\/div>\n\t\t\t\t<div class=\"man_adv_box_block\">\n\t\t\t\t\t<div class=\"man_adv_box_block_cont_wb man_wht_txt\">\n\t\t\t\t\t\t<h4>02<\/h4>\n\t\t\t\t\t\t<h2>Ricerca e Sviluppo<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"man_adv_box_block_cont man_wht_txt\">\n\t\t\t\t\t\t<h4>02<\/h4>\n\t\t\t\t\t\t<h2>Ricerca e Sviluppo<\/h2>\n\t\t\t\t\t\t<p>Tutte le fasi di progettazione concettuale, simulazione virtuale e gestione del progetto all&#039;interno del processo di progettazione del nuovo prodotto vengono eseguite da personale esperto nel centro di ricerca e sviluppo di Tirsan Kardan.<\/p>\n\t\t\t\t\t\t<a href=\"https:\/\/tirsankardan.com\/it\/\/it\/centro-di-ricerca-e-sviluppo\/#ricerca\" class=\"btn btn_transparent\">Di pi\u00f9<i class=\"ti ti-arrow-right\"><\/i><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"man_adv_box\" id=\"6527d41\">\n\t\t\t\t<div class=\"man_adv_box_img man_image_bck man_adv_box_img_6527d41\" data-image=\"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/bilgi-guvenligi-1600x1066.jpg\"><\/div>\n\t\t\t\t<div class=\"man_adv_box_block\">\n\t\t\t\t\t<div class=\"man_adv_box_block_cont_wb man_wht_txt\">\n\t\t\t\t\t\t<h4>03<\/h4>\n\t\t\t\t\t\t<h2>Diritti di Proprieta\u2019 Intellettuale<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"man_adv_box_block_cont man_wht_txt\">\n\t\t\t\t\t\t<h4>03<\/h4>\n\t\t\t\t\t\t<h2>Diritti di Proprieta\u2019 Intellettuale<\/h2>\n\t\t\t\t\t\t<p>Uno degli obiettivi principali del Tirsan Kardan R&amp;D Center \u00e8 quello di sviluppare continuamente il proprio portafoglio di proprieta\u2019 intellettuale producendo progetti che creano valore aggiunto e includono idee innovative.<\/p>\n\t\t\t\t\t\t<a href=\"https:\/\/tirsankardan.com\/it\/\/it\/centro-di-ricerca-e-sviluppo\/#diritti\" class=\"btn btn_transparent\">Di pi\u00f9<i class=\"ti ti-arrow-right\"><\/i><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n\n\t<script type=\"text\/javascript\">\n\n\t\tjQuery(document).ready(function($) {\n\t\t\t\/\/ Advantages\n\t\t\t$('.man_adv_carousel .man_adv_box_img').each(function(i, el){\n\t\t\t\tif ( i === 0) {\n\t\t\t\t\t\t$(el).addClass('first-item');\n\t\t\t\t}\n\t\t\t\t$(this).insertBefore($(this).parents('.elementor-container'));\n\t\t\t});\n\t\t\t$('.man_adv_box').on({\n\t\t\t\tmouseenter:function(){\n\t\t\t\t\tvar box_id = $(this).attr('id');\n\t\t\t\t\t$('.man_adv_box_img_'+box_id+'').addClass('active');\n\t\t\t\t},mouseleave:function(){\n\t\t\t\t\tvar box_id = $(this).attr('id');\n\t\t\t\t\t$('.man_adv_box_img_'+box_id+'').removeClass('active');\n\t\t\t\t}\n\t\t\t});\n\n\t\t\t$('.man_adv_carousel').each(function(){\n\t\t\t\tvar items = $(this).attr('data-items');\n\t\t\t\t$(this).owlCarousel({\n\t\t\t\t\titems:items,\n\t\t\t\t\tautoplay:0,\n\t\t\t\t\tdots:1,\n\t\t\t\t\tnav:1,\n\t\t\t\t\tnavText:['<i class=\"ti ti-angle-left\"><\/i>','<i class=\"ti ti-angle-right\"><\/i>']\n\t\t\t\t});\n\t\t\t});\n\n\t\t});\n\t<\/script>\n\n\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69054a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69054a0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8bec390\" data-id=\"8bec390\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ae12f8 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ae12f8\" data-element_type=\"section\" id=\"test-it\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30b33b9\" data-id=\"30b33b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33b96ea elementor-widget elementor-widget-text-editor\" data-id=\"33b96ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 style=\"text-align: left;\"><span style=\"color: #2e3192;\">Test e Verifica<\/span><\/h2>\n<p style=\"text-align: left;\">Il nostro centro di test, situato all&#8217;interno del centro di ricerca e sviluppo Tirsan Kardan, dispone di un&#8217;eccellente infrastruttura in grado di eseguire tutte le verifiche di prodotto e di processo, dal livello del prodotto assemblato ai componenti indipendenti.<\/p>\n<p style=\"text-align: left;\">Verifichiamo inoltre le prestazioni dei nostri prodotti con test fisici accelerati che simulano le condizioni reali del campo, dopo test e simulazioni eseguiti in ambiente virtuale.<\/p>\n<p style=\"text-align: left;\">Applichiamo speciali piani di prova che sono stati progettati dal nostro personale esperto nella durabilita\u2019 strutturale e dinamica, nel comfort acustico e nell&#8217; impatto ambientale, i cui risultati sono stati verificati con le reali condizioni di campo.<\/p>\n<p style=\"text-align: left;\">Con il simulatore stradale di veicoli commerciali pesanti con sistema di fanghi integrato, il cui investimento \u00e8 appena stato completato, possiamo spremere i test di resistenza a livello di veicolo che durano 8-10 mesi in un programma di test a livello di laboratorio ristretto come 8 settimane.<\/p>\n<p style=\"text-align: left;\">Oltre ai test e alla verifica dei nuovi prototipi di prodotto nel nostro Test Center, vengono effettuati anche test periodici delle prestazioni dei nostri prodotti in serie.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d38269\" data-id=\"9d38269\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c0ee88b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0ee88b\" data-element_type=\"section\" id=\"ricerca\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c89256e\" data-id=\"c89256e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-23d8ce5\" data-id=\"23d8ce5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb3c6a8 elementor-widget elementor-widget-text-editor\" data-id=\"fb3c6a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 style=\"text-align: left;\"><span style=\"color: #2e3192;\">Ricerca e Sviluppo<\/span><\/h2>\n<p style=\"text-align: left;\">Tutte le fasi di progettazione concettuale, simulazione virtuale e gestione del progetto all&#8217;interno del processo di progettazione del nuovo prodotto vengono eseguite da personale esperto nel centro di ricerca e sviluppo di Tirsan Kardan.<\/p>\n<p style=\"text-align: left;\">I nostri prodotti sono testati principalmente in ambiente virtuale, utilizzando le piu\u2019 avanzate metodologie di progettazione e analisi assistita da computer, per condizioni operative reali sul campo nei settori della durabilita\u2019 strutturale e dinamica, della sicurezza, delle vibrazioni meccaniche e dell&#8217;acustica. Pertanto, viene eliminata la necessita\u2019 di alcuni test di laboratorio e a livello di strumento, i tempi del ciclo di progettazione del prodotto e i costi del prodotto sono ridotti.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb860ca elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb860ca\" data-element_type=\"section\" id=\"diritti\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-56a2ca3\" data-id=\"56a2ca3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f15fb3 elementor-widget elementor-widget-text-editor\" data-id=\"0f15fb3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-133cc86 elementor-widget elementor-widget-heading\" data-id=\"133cc86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<h2 style=\"text-align: left;\"><span style=\"color: #2e3192;\">Diritti di Proprieta\u2019 Intellettuale<\/span><\/h2>\n<div class=\"elementor-widget-container\" style=\"text-align: left;\">\n<p>Uno degli obiettivi principali del Tirsan Kardan R&amp;D Center \u00e8 quello di sviluppare continuamente il proprio portafoglio di proprieta\u2019 intellettuale producendo progetti che creano valore aggiunto e includono idee innovative.<\/p>\n<\/div>\n<div style=\"text-align: left;\"> <\/div>\n<div class=\"elementor-widget-container\" style=\"text-align: left;\">\n<p>Tra 2016-18 anni del nostro portafoglio di diritti di proprieta\u2019 intellettuale aumentato di 2 volte, nel 2019 \u00e8 registrato in Turchia nelle prime 50 , mentre i modelli di utilit\u00e0 sono stati registrati nelle prime 10 aziende. Tra le aziende che operano nel settore automobilistico, siamo tra le prime 10 aziende per numero di registrazioni di brevetti e le prime 3 per numero di registrazioni di modelli di utilita\u2019.<\/p>\n<\/div>\n<p>Riteniamo che il nostro ritmo in graduale accelerazione portera\u2019 la nostra azienda a livelli piu\u2019 alti nel 2020 e dopo.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-32f6d88\" data-id=\"32f6d88\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6909b89 elementor-widget elementor-widget-spacer\" data-id=\"6909b89\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-768ee18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"768ee18\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e940fd9 elementor-invisible\" data-id=\"e940fd9\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c95744f elementor-widget elementor-widget-counter\" data-id=\"c95744f\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.5.3 - 28-12-2021 *\/\n.elementor-counter .elementor-counter-number-wrapper{display:-webkit-box;display:-ms-flexbox;display:flex;font-size:69px;font-weight:600;line-height:1}.elementor-counter .elementor-counter-number-prefix,.elementor-counter .elementor-counter-number-suffix{-webkit-box-flex:1;-ms-flex-positive:1;flex-grow:1;white-space:pre-wrap}.elementor-counter .elementor-counter-number-prefix{text-align:right}.elementor-counter .elementor-counter-number-suffix{text-align:left}.elementor-counter .elementor-counter-title{text-align:center;font-size:19px;font-weight:400;line-height:2.5}<\/style>\t\t<div class=\"elementor-counter man_no_prefix elementor-counter-flex man_no_suffix\">\n\t\t\t\t\t\t<div class=\"elementor-icon\"><i class=\"ti-write\"><\/i><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper_flex\">\n\t\t\t\n\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\n\t\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t\t<span class=\"elementor-counter-number\" data-delimiter=\",\" data-duration=\"2000\"  data-to-value=\"851\">0<\/span>\n\t\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-counter-title\">Domanda di brevetto<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4dcc9ef elementor-invisible\" data-id=\"4dcc9ef\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79acb43 elementor-widget elementor-widget-counter\" data-id=\"79acb43\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter man_no_prefix elementor-counter-flex man_no_suffix\">\n\t\t\t\t\t\t<div class=\"elementor-icon\"><i class=\"ti-stamp\"><\/i><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper_flex\">\n\t\t\t\n\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\n\t\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t\t<span class=\"elementor-counter-number\" data-delimiter=\",\" data-duration=\"4000\"  data-to-value=\"197\">0<\/span>\n\t\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-counter-title\">Brevetto approvato<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7c8af9d elementor-invisible\" data-id=\"7c8af9d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f63df3 elementor-widget elementor-widget-counter\" data-id=\"1f63df3\" data-element_type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-counter man_no_prefix elementor-counter-flex man_no_suffix\">\n\t\t\t\t\t\t<div class=\"elementor-icon\"><i class=\"business-investment\"><\/i><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-counter-number-wrapper_flex\">\n\t\t\t\n\t\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\n\t\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t\t<span class=\"elementor-counter-number\" data-delimiter=\",\" data-duration=\"4000\"  data-to-value=\"198\">0<\/span>\n\t\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-counter-title\">Invenzione mondiale<\/div>\n\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Generale Il centro di ricerca e sviluppo Tirsan Kardan \u00e8 stato approvato e registrato dal Ministero dell&#8217;Industria e&#8230;<\/p>\n","protected":false},"author":10,"featured_media":5152,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3911","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro di Ricerca e Sviluppo - Tirsan Kardan<\/title>\n<meta name=\"description\" content=\"Il nostro centro di ricerca e sviluppo, risultato della valutazione delle prestazioni condotta dal ministero dell&#039;Industria e della tecnologia nel 2018 \u00e9 stato il gruppo che ha ricevuto il primo premio nei centri di ricerca e sviluppo in Turchia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro di Ricerca e Sviluppo - Tirsan Kardan\" \/>\n<meta property=\"og:description\" content=\"Il nostro centro di ricerca e sviluppo, risultato della valutazione delle prestazioni condotta dal ministero dell&#039;Industria e della tecnologia nel 2018 \u00e9 stato il gruppo che ha ricevuto il primo premio nei centri di ricerca e sviluppo in Turchia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirsan Kardan\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-12T13:46:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/IMG-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/\",\"url\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/\",\"name\":\"Centro di Ricerca e Sviluppo - Tirsan Kardan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tirsankardan.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG-2.jpg\",\"datePublished\":\"2021-09-22T11:35:12+00:00\",\"dateModified\":\"2021-10-12T13:46:10+00:00\",\"description\":\"Il nostro centro di ricerca e sviluppo, risultato della valutazione delle prestazioni condotta dal ministero dell'Industria e della tecnologia nel 2018 \u00e9 stato il gruppo che ha ricevuto il primo premio nei centri di ricerca e sviluppo in Turchia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tirsankardan.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG-2.jpg\",\"contentUrl\":\"https:\\\/\\\/tirsankardan.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG-2.jpg\",\"width\":1600,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/centro-di-ricerca-e-sviluppo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro di Ricerca e Sviluppo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/\",\"name\":\"Tirsan Kardan\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/#organization\",\"name\":\"Tirsan Kardan A\u015e\",\"url\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirsankardan.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/tirsankardan.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo.png\",\"width\":314,\"height\":69,\"caption\":\"Tirsan Kardan A\u015e\"},\"image\":{\"@id\":\"https:\\\/\\\/tirsankardan.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro di Ricerca e Sviluppo - Tirsan Kardan","description":"Il nostro centro di ricerca e sviluppo, risultato della valutazione delle prestazioni condotta dal ministero dell'Industria e della tecnologia nel 2018 \u00e9 stato il gruppo che ha ricevuto il primo premio nei centri di ricerca e sviluppo in Turchia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/","og_locale":"it_IT","og_type":"article","og_title":"Centro di Ricerca e Sviluppo - Tirsan Kardan","og_description":"Il nostro centro di ricerca e sviluppo, risultato della valutazione delle prestazioni condotta dal ministero dell'Industria e della tecnologia nel 2018 \u00e9 stato il gruppo che ha ricevuto il primo premio nei centri di ricerca e sviluppo in Turchia.","og_url":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/","og_site_name":"Tirsan Kardan","article_modified_time":"2021-10-12T13:46:10+00:00","og_image":[{"width":1600,"height":640,"url":"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/IMG-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/","url":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/","name":"Centro di Ricerca e Sviluppo - Tirsan Kardan","isPartOf":{"@id":"https:\/\/tirsankardan.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/#primaryimage"},"image":{"@id":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/#primaryimage"},"thumbnailUrl":"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/IMG-2.jpg","datePublished":"2021-09-22T11:35:12+00:00","dateModified":"2021-10-12T13:46:10+00:00","description":"Il nostro centro di ricerca e sviluppo, risultato della valutazione delle prestazioni condotta dal ministero dell'Industria e della tecnologia nel 2018 \u00e9 stato il gruppo che ha ricevuto il primo premio nei centri di ricerca e sviluppo in Turchia.","breadcrumb":{"@id":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/#primaryimage","url":"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/IMG-2.jpg","contentUrl":"https:\/\/tirsankardan.com\/wp-content\/uploads\/2021\/10\/IMG-2.jpg","width":1600,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/tirsankardan.com\/it\/centro-di-ricerca-e-sviluppo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/tirsankardan.com\/it\/"},{"@type":"ListItem","position":2,"name":"Centro di Ricerca e Sviluppo"}]},{"@type":"WebSite","@id":"https:\/\/tirsankardan.com\/it\/#website","url":"https:\/\/tirsankardan.com\/it\/","name":"Tirsan Kardan","description":"","publisher":{"@id":"https:\/\/tirsankardan.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirsankardan.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tirsankardan.com\/it\/#organization","name":"Tirsan Kardan A\u015e","url":"https:\/\/tirsankardan.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tirsankardan.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/tirsankardan.com\/wp-content\/uploads\/2018\/07\/logo.png","contentUrl":"https:\/\/tirsankardan.com\/wp-content\/uploads\/2018\/07\/logo.png","width":314,"height":69,"caption":"Tirsan Kardan A\u015e"},"image":{"@id":"https:\/\/tirsankardan.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/pages\/3911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/comments?post=3911"}],"version-history":[{"count":5,"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/pages\/3911\/revisions"}],"predecessor-version":[{"id":5119,"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/pages\/3911\/revisions\/5119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/media\/5152"}],"wp:attachment":[{"href":"https:\/\/tirsankardan.com\/it\/wp-json\/wp\/v2\/media?parent=3911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}